{"id":498,"date":"2024-05-11T01:48:10","date_gmt":"2024-05-11T01:48:10","guid":{"rendered":"https:\/\/hhs.purdue.edu\/aerosol\/?page_id=498"},"modified":"2026-06-14T02:27:27","modified_gmt":"2026-06-14T02:27:27","slug":"national-international-conferences","status":"publish","type":"page","link":"https:\/\/hhs.purdue.edu\/aerosol\/national-international-conferences\/","title":{"rendered":"National\/International Conferences"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":89,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-498","page","type-page","status-publish","hentry"],"pp_force_visibility":null,"pp_subpost_visibility":null,"pp_inherited_force_visibility":null,"pp_inherited_subpost_visibility":null,"acf":[],"_links":{"self":[{"href":"https:\/\/hhs.purdue.edu\/aerosol\/wp-json\/wp\/v2\/pages\/498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hhs.purdue.edu\/aerosol\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hhs.purdue.edu\/aerosol\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hhs.purdue.edu\/aerosol\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/hhs.purdue.edu\/aerosol\/wp-json\/wp\/v2\/comments?post=498"}],"version-history":[{"count":26,"href":"https:\/\/hhs.purdue.edu\/aerosol\/wp-json\/wp\/v2\/pages\/498\/revisions"}],"predecessor-version":[{"id":3374,"href":"https:\/\/hhs.purdue.edu\/aerosol\/wp-json\/wp\/v2\/pages\/498\/revisions\/3374"}],"wp:attachment":[{"href":"https:\/\/hhs.purdue.edu\/aerosol\/wp-json\/wp\/v2\/media?parent=498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}