{"id":688,"date":"2023-04-10T19:51:30","date_gmt":"2023-04-10T19:51:30","guid":{"rendered":"https:\/\/hhs.purdue.edu\/miller-child-lab-school\/?page_id=688"},"modified":"2026-06-25T19:38:41","modified_gmt":"2026-06-25T19:38:41","slug":"our-people","status":"publish","type":"page","link":"https:\/\/hhs.purdue.edu\/miller-child-lab-school\/our-people\/","title":{"rendered":"Our People"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":39,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-688","page","type-page","status-publish","hentry"],"pp_force_visibility":null,"pp_subpost_visibility":null,"pp_inherited_force_visibility":null,"pp_inherited_subpost_visibility":null,"_links":{"self":[{"href":"https:\/\/hhs.purdue.edu\/miller-child-lab-school\/wp-json\/wp\/v2\/pages\/688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hhs.purdue.edu\/miller-child-lab-school\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hhs.purdue.edu\/miller-child-lab-school\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hhs.purdue.edu\/miller-child-lab-school\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/hhs.purdue.edu\/miller-child-lab-school\/wp-json\/wp\/v2\/comments?post=688"}],"version-history":[{"count":169,"href":"https:\/\/hhs.purdue.edu\/miller-child-lab-school\/wp-json\/wp\/v2\/pages\/688\/revisions"}],"predecessor-version":[{"id":3163,"href":"https:\/\/hhs.purdue.edu\/miller-child-lab-school\/wp-json\/wp\/v2\/pages\/688\/revisions\/3163"}],"wp:attachment":[{"href":"https:\/\/hhs.purdue.edu\/miller-child-lab-school\/wp-json\/wp\/v2\/media?parent=688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}